{"id":3,"date":"2024-03-30T01:41:16","date_gmt":"2024-03-30T00:41:16","guid":{"rendered":"http:\/\/wiapro-solar.com\/wiapro\/?page_id=3"},"modified":"2024-07-08T14:09:40","modified_gmt":"2024-07-08T12:09:40","slug":"politique-de-confidentialite","status":"publish","type":"page","link":"https:\/\/wiapro-solar.com\/wiapro\/politique-de-confidentialite\/","title":{"rendered":"Politique de confidentialit\u00e9"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"3\" class=\"elementor elementor-3\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"has_eae_slider aux-parallax-section elementor-element elementor-element-1c9f41e8 e-flex e-con-boxed e-con e-parent\" data-eae-slider=\"21259\" data-id=\"1c9f41e8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-beac47e elementor-widget elementor-widget-heading\" data-id=\"beac47e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Politique de Confidentialit\u00e9<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-74c1310f elementor-widget elementor-widget-text-editor\" data-id=\"74c1310f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ol><li><strong> Introduction<\/strong><\/li><\/ol><p>Bienvenue sur <strong><a href=\"http:\/\/www.wiapro-solar.com\">www.wiapro-solar.com<\/a><\/strong>. La protection de vos donn\u00e9es personnelles est notre priorit\u00e9. Cette Politique de Confidentialit\u00e9 d\u00e9crit comment nous collectons, utilisons et prot\u00e9geons vos informations personnelles lorsque vous utilisez notre site web.<\/p><ol start=\"2\"><li><strong> Pr\u00e9sentation du site internet<\/strong><\/li><\/ol><p>Le site internet <strong><a href=\"http:\/\/www.wiapro-solar.com\">www.wiapro-solar.com<\/a><\/strong> est \u00e9dit\u00e9 par la soci\u00e9t\u00e9 <strong>Wiapro-Solar<\/strong>, dont le si\u00e8ge social est situ\u00e9 au <strong>20 Rue Theron de Montauge, 31200 Toulouse, France<\/strong>. Notre site a pour vocation de pr\u00e9senter nos produits et services dans le domaine de l&rsquo;\u00e9nergie solaire, de fournir des informations sur les \u00e9nergies renouvelables et de permettre \u00e0 nos clients et prospects de nous contacter facilement pour toute question ou demande de devis.<\/p><p><strong>2.1. Objet du site<\/strong><\/p><p>Le site <strong><a href=\"http:\/\/www.wiapro-solar.com\">www.wiapro-solar.com<\/a><\/strong> vise \u00e0 :<\/p><ul><li>Informer les visiteurs sur les produits et services offerts par Wiapro-Solar<\/li><li>Fournir des ressources \u00e9ducatives sur l&rsquo;\u00e9nergie solaire et les \u00e9nergies renouvelables<\/li><li>Permettre aux visiteurs de demander des informations suppl\u00e9mentaires ou des devis via des formulaires de contact<\/li><li>Offrir un support client en ligne<\/li><li>Publier des actualit\u00e9s et des mises \u00e0 jour concernant l&rsquo;industrie solaire et les projets de l&rsquo;entreprise<\/li><\/ul><p><strong>2.2. Acc\u00e8s et utilisation<\/strong><\/p><p>L&rsquo;acc\u00e8s au site <strong><a href=\"http:\/\/www.wiapro-solar.com\">www.wiapro-solar.com<\/a><\/strong> est gratuit. Les visiteurs peuvent naviguer sur le site pour consulter les informations disponibles sans avoir \u00e0 fournir des donn\u00e9es personnelles, sauf dans les cas o\u00f9 ils choisissent de remplir un formulaire de contact ou de demande de devis. Toute utilisation du site implique l&rsquo;acceptation de la pr\u00e9sente Politique de Confidentialit\u00e9 et des Conditions G\u00e9n\u00e9rales d&rsquo;Utilisation.<\/p><p><strong>2.3. Propri\u00e9taire, Responsable de Publication et H\u00e9bergeur<\/strong><\/p><ul><li><strong>Propri\u00e9taire<\/strong> : SAS <strong>WIAPRO-SOLAR<\/strong>, 20 Rue Theron de Montauge, 31200 Toulouse, France, <strong>SIRET<\/strong> : 98132267000010.<\/li><li><strong>Responsable de Publication<\/strong> : Service Informatique WS, contact@wiapro-solar.com<\/li><li><strong>H\u00e9bergeur<\/strong> : <strong>OVH<\/strong>, 2 Rue Kellermann, 59100 Roubaix, France<\/li><\/ul><ol start=\"3\"><li><strong> Collecte des Informations<\/strong><\/li><\/ol><p>Nous collectons plusieurs types d&rsquo;informations pour divers objectifs afin de vous fournir et am\u00e9liorer notre service :<\/p><p><strong>3.1. Informations Personnelles<\/strong><\/p><p>Lorsque vous utilisez notre site, nous pouvons vous demander de nous fournir certaines informations personnelles identifiables, y compris mais sans s&rsquo;y limiter :<\/p><ul><li>Nom<\/li><li>Adresse e-mail<\/li><li>Num\u00e9ro de t\u00e9l\u00e9phone<\/li><li>Adresse postale<\/li><\/ul><p><strong>3.2. Donn\u00e9es de Navigation<\/strong><\/p><p>Nous collectons \u00e9galement des informations que votre navigateur envoie chaque fois que vous visitez notre site, telles que :<\/p><ul><li>Adresse IP<\/li><li>Type de navigateur<\/li><li>Pages visit\u00e9es<\/li><li>Heure et date de la visite<\/li><li>Temps pass\u00e9 sur ces pages<\/li><\/ul><ol start=\"4\"><li><strong> Utilisation des Informations<\/strong><\/li><\/ol><p>Nous utilisons les informations collect\u00e9es \u00e0 diverses fins, notamment :<\/p><ul><li>Pour fournir et maintenir notre service<\/li><li>Pour vous notifier des changements apport\u00e9s \u00e0 notre service<\/li><li>Pour vous permettre de participer aux fonctionnalit\u00e9s interactives de notre service lorsque vous le souhaitez<\/li><li>Pour fournir un support client<\/li><li>Pour recueillir des analyses ou des informations pr\u00e9cieuses afin d&rsquo;am\u00e9liorer notre service<\/li><li>Pour surveiller l&rsquo;utilisation de notre service<\/li><li>Pour d\u00e9tecter, pr\u00e9venir et r\u00e9soudre les probl\u00e8mes techniques<\/li><\/ul><ol start=\"5\"><li><strong> Partage des Informations<\/strong><\/li><\/ol><p>Nous ne vendons, n&rsquo;\u00e9changeons ni ne transf\u00e9rons de quelque mani\u00e8re que ce soit vos informations personnelles identifiables \u00e0 des tiers sans votre consentement, sauf dans les cas suivants :<\/p><ul><li>Aux prestataires de services qui nous aident \u00e0 exploiter notre site ou \u00e0 mener nos affaires, tant que ces parties conviennent de garder ces informations confidentielles. Par exemple, nous travaillons avec des prestataires de services tiers pour l&rsquo;h\u00e9bergement du site, l&rsquo;analyse de donn\u00e9es, et les services de paiement.<\/li><li>Lorsque nous croyons que la divulgation est appropri\u00e9e pour se conformer \u00e0 la loi, appliquer les politiques de notre site, ou prot\u00e9ger nos droits, notre propri\u00e9t\u00e9 ou notre s\u00e9curit\u00e9, ainsi que ceux d&rsquo;autres personnes<\/li><\/ul><ol start=\"6\"><li><strong> S\u00e9curit\u00e9 des Donn\u00e9es<\/strong><\/li><\/ol><p>La s\u00e9curit\u00e9 de vos donn\u00e9es est importante pour nous. Nous mettons en \u0153uvre une vari\u00e9t\u00e9 de mesures de s\u00e9curit\u00e9 pour maintenir la s\u00e9curit\u00e9 de vos informations personnelles, y compris l&rsquo;utilisation de cryptage SSL, de pare-feu s\u00e9curis\u00e9 et de protocoles d&rsquo;acc\u00e8s restreint. Cependant, aucune m\u00e9thode de transmission sur Internet ou m\u00e9thode de stockage \u00e9lectronique n&rsquo;est s\u00e9curis\u00e9e \u00e0 100%. Par cons\u00e9quent, nous ne pouvons garantir une s\u00e9curit\u00e9 absolue.<\/p><ol start=\"7\"><li><strong> Vos Droits<\/strong><\/li><\/ol><p>Vous avez le droit de :<\/p><ul><li>Acc\u00e9der \u00e0 vos donn\u00e9es personnelles que nous d\u00e9tenons<\/li><li>Rectifier des informations inexactes ou incompl\u00e8tes<\/li><li>Demander la suppression de vos donn\u00e9es personnelles<\/li><li>Restreindre ou s&rsquo;opposer au traitement de vos donn\u00e9es personnelles<\/li><li>Demander la portabilit\u00e9 de vos donn\u00e9es personnelles<\/li><\/ul><ol start=\"8\"><li><strong> Modifications de la Politique de Confidentialit\u00e9<\/strong><\/li><\/ol><p>Nous pouvons mettre \u00e0 jour notre Politique de Confidentialit\u00e9 de temps en temps. Nous vous informerons de tout changement en publiant la nouvelle Politique de Confidentialit\u00e9 sur cette page. Nous vous encourageons \u00e0 consulter r\u00e9guli\u00e8rement cette page pour prendre connaissance des \u00e9ventuelles modifications. Cette politique a \u00e9t\u00e9 mise \u00e0 jour pour la derni\u00e8re fois le <b>01\/03\/2024<\/b>. Nous mettons \u00e0 jour cette politique chaque 6 mois.<\/p><ol start=\"9\"><li><strong> Nous Contacter<\/strong><\/li><\/ol><p>Si vous avez des questions concernant cette Politique de Confidentialit\u00e9, veuillez nous contacter :<\/p><ul><li>Par email : <strong>contact@wiapro-solar.com<\/strong><\/li><li>Par t\u00e9l\u00e9phone : <strong>+33 5 82 95 11 63<\/strong><\/li><li>Par courrier : <strong>20 Rue Theron de Montauge, 31200 Toulouse, France<\/strong><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Politique de Confidentialit\u00e9 Introduction Bienvenue sur www.wiapro-solar.com. La protection de vos donn\u00e9es personnelles est notre priorit\u00e9. Cette Politique de Confidentialit\u00e9 d\u00e9crit comment nous collectons, utilisons et prot\u00e9geons vos informations personnelles lorsque vous utilisez notre site web. Pr\u00e9sentation du site internet Le site internet www.wiapro-solar.com est \u00e9dit\u00e9 par la soci\u00e9t\u00e9 Wiapro-Solar, dont le si\u00e8ge social est [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_angie_page":false,"footnotes":""},"class_list":["post-3","page","type-page","status-publish","hentry"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/wiapro-solar.com\/wiapro\/wp-json\/wp\/v2\/pages\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wiapro-solar.com\/wiapro\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/wiapro-solar.com\/wiapro\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/wiapro-solar.com\/wiapro\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wiapro-solar.com\/wiapro\/wp-json\/wp\/v2\/comments?post=3"}],"version-history":[{"count":16,"href":"https:\/\/wiapro-solar.com\/wiapro\/wp-json\/wp\/v2\/pages\/3\/revisions"}],"predecessor-version":[{"id":5581,"href":"https:\/\/wiapro-solar.com\/wiapro\/wp-json\/wp\/v2\/pages\/3\/revisions\/5581"}],"wp:attachment":[{"href":"https:\/\/wiapro-solar.com\/wiapro\/wp-json\/wp\/v2\/media?parent=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}